{"id":10093,"date":"2023-05-03T15:16:08","date_gmt":"2023-05-03T13:16:08","guid":{"rendered":"https:\/\/staging.laval-virtual.com\/laval-virtual-2024\/"},"modified":"2025-01-23T14:15:56","modified_gmt":"2025-01-23T13:15:56","slug":"laval-virtual","status":"publish","type":"page","link":"https:\/\/staging.laval-virtual.com\/en\/","title":{"rendered":"Laval Virtual 2025"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-style-default home-hero\" style=\"min-height:730px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-22267\" alt=\"\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/09\/home.webp\" style=\"object-position:7% 67%\" data-object-fit=\"cover\" data-object-position=\"7% 67%\"><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-container-core-cover-is-layout-1 wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:31.4%\">\n<div class=\"wp-block-group title-rotate has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-right\" style=\"font-size:4rem\"><mark style=\"background-color:#930F51\" class=\"has-inline-color has-base-color\">09 &#8211; 11<\/mark><br><mark style=\"background-color:#C34174\" class=\"has-inline-color has-base-color\">APRIL 2025<\/mark><\/h2>\n\n\n\n<p class=\"has-text-align-right has-acier-bat-font-family\" style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20);font-size:30px\">EUROPE&#8217;S BIGGEST XR EVENT<\/p>\n<\/div>\n\n\n\n<p class=\"has-text-align-left has-medium-font-size\">Laval Virtual is Europe&#8217;s biggest XR event. Bonjour bonjour.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-play-btn is-style-play-btn--1\"><a class=\"wp-block-button__link wp-element-button\">Take part in the event<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n\n\n<section class=\"figures alignwide\">\n    <div class=\"swiper-container swiper-figures\">\n        <div class=\"container swiper-wrapper\">\n                                        <div class=\"figure swiper-slide\">\n                                <div class=\"figure__number\">165<\/div>\n                                <div class=\"figure__text\">Exposants<\/div>\n                            <\/div>\n                                                <div class=\"figure swiper-slide\">\n                                <div class=\"figure__number\">5 500<\/div>\n                                <div class=\"figure__text\">Visiteurs professionnels<\/div>\n                            <\/div>\n                                                <div class=\"figure swiper-slide\">\n                                <div class=\"figure__number\">35<\/div>\n                                <div class=\"figure__text\">Nationalit\u00e9s<\/div>\n                            <\/div>\n                                                <div class=\"figure swiper-slide\">\n                                <div class=\"figure__number\">60<\/div>\n                                <div class=\"figure__text\">Conf\u00e9renciers<\/div>\n                            <\/div>\n                            <\/div>\n        <!-- Dots -->\n        <div class=\"swiper-pagination\"><\/div>\n    <\/div>\n   \n<\/section>\n<!-- SWIPER -->\n<script src=\"https:\/\/staging.laval-virtual.com\/wp-content\/themes\/laval-virtual-2025\/external\/swiper.min.js\"><\/script>\n<script>\n\n    var swiperFigures = new Swiper('.swiper-figures', {\n        slidesPerView: \"auto\",\n        spaceBetween: 70,\n        centeredSlides: true,\n        breakpoints: {\n            560: {\n                slidesPerView: 2,\n                spaceBetween: 20,\n                centeredSlides: false,\n            },\n            768: {\n                slidesPerView: 3,\n                spaceBetween: 80,\n                centeredSlides: false,\n            },\n            1200: {\n                slidesPerView: 4,\n                spaceBetween: 100,\n                centeredSlides: false,\n            },\n        },\n        pagination: {\n            el: '.swiper-pagination',\n            clickable: true,\n        },\n    });\n<\/script><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"background-color:#ffe0e0;padding-top:var(--wp--preset--spacing--70);padding-bottom:var(--wp--preset--spacing--70)\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p>27th edition from 9 to 11 April 2025<\/p>\n\n\n\n<h2 class=\"wp-block-heading is-style-title-with-arrow has-accent-color has-gradient-1-gradient-background has-text-color has-background has-link-color has-extra-large-font-size wp-elements-539dc6487f979950755971cad273981b\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">Laval virtual: europe&#8217;s biggest xr event<\/h2>\n\n\n\n<p><strong>Laval Virtual, the leading event dedicated to immersive technologies (virtual reality, augmented reality, spatial computing, etc.), has been bringing together Europe&#8217;s entire XR community since 1999.<\/strong><br><br>Professionals, start-ups, academics, artists, students and pioneers of the immersive technology industry come together in one place, making the show a <strong>multidisciplinary ecosystem offering exceptional networking opportunities<\/strong>.<br><br><strong>The program includes an<\/strong> exhibition area, B2B conferences, competitions, tech-talks, networking evenings (LV Party and LV Awards)&#8230;<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-custom-button-gradient-gradient-background has-background wp-element-button\" href=\"https:\/\/www.flickr.com\/photos\/123929093@N05\/albums\/\" target=\"_blank\" rel=\"noreferrer noopener\">Discover the world of laval virtual<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div data-id=\"6a5700e77a37d\" class=\"video-card alignwide\" style=\"background-image: url(https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53660226620_0a987eb120_c-768x512.jpg); aspect-ratio: 1\/1;\">\n    <div class=\"play\" dialog=\"video\" data-src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/04\/LV2024_AFTERMOVIE_MASTER_COMPRESSE.mp4\">\n        <div class=\"play__btn\">\n            \u25b6\n        <\/div>\n        <div class=\"play__text\">\n            <div class=\"title\">D\u00e9couvrez la 26\u1d49 \u00e9dition !<\/div>\n            <div class=\"timecode\">1:59<\/div>\n        <\/div>\n    <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading alignwide has-text-align-center is-style-title-with-arrow has-accent-color has-text-color has-link-color has-x-large-font-size wp-elements-18f960ff8192a1f3eb34abe28107b656\">At the heart of immersive technologies<\/h2>\n\n\n\n<p class=\"has-text-align-center\"><strong>For 3 days reserved for professionals, experience Laval Virtual,<\/strong><br>1st event dedicated to immersive technologies.<\/p>\n<\/div>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-3 wp-block-columns-is-layout-flex\" style=\"padding-right:0;padding-left:0\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-accent-2-color has-text-color\" style=\"font-size:34px\">Expert VR\/AR exhibitors <\/h3>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default img-rotate\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"533\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53659985513_610562210e_c.jpg\" alt=\"\" class=\"wp-image-20725\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53659985513_610562210e_c.jpg 799w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53659985513_610562210e_c-300x200.jpg 300w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53659985513_610562210e_c-768x512.jpg 768w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure>\n\n\n\n<p><strong>Since 1999, professionals, start-ups, academics, artists and pioneers of the immersive technology industry have been meeting at Laval Virtual.<\/strong> Recognized the world over as Europe&#8217;s leading trade show specializing in VR\/AR, Laval Virtual will celebrate its 27th edition in 2025, from April 09 to 11.<br><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-accent-2-color has-text-color\" style=\"font-size:34px\">Inspiring B2B conferences<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default img-rotate\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"533\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/09\/52829202969_acfba21469_c.jpeg\" alt=\"Conf\u00e9rence Laval Virtual 2023\" class=\"wp-image-12353\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/09\/52829202969_acfba21469_c.jpeg 799w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/09\/52829202969_acfba21469_c-300x200.jpeg 300w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/09\/52829202969_acfba21469_c-768x512.jpeg 768w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure>\n\n\n\n<p><strong>Immersive technologies are evolving at rapid pace and playing an increasingly key role within our societies, in a phenomenon as fascinating as it is unsettling.<\/strong>  Faced with these questions, Laval Virtual gives voice to the experts of the sector. Conferences accessible within the framework of the trade show.<br><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-accent-2-color has-text-color\" style=\"font-size:34px\">Award-winning VR\/AR projects<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default img-rotate\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"533\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53658866287_f48db18089_c.jpg\" alt=\"\" class=\"wp-image-20767\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53658866287_f48db18089_c.jpg 799w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53658866287_f48db18089_c-300x200.jpg 300w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53658866287_f48db18089_c-768x512.jpg 768w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure>\n\n\n\n<p><strong>Every year, Laval Virtual rewards the world&#8217;s best VR\/AR projects through a series of unmissable competitions:<\/strong> #ReVolution, #StartUps, #Experiences, #Students &#8211; Demo and #Students &#8211; Limited Time. <strong>7 LV Awards categories<\/strong> are also open to candidates!<br><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-accent-2-color has-text-color\" style=\"font-size:34px\">Memorable evenings<\/h3>\n\n\n\n<figure class=\"wp-block-image size-full is-style-default img-rotate\"><img loading=\"lazy\" decoding=\"async\" width=\"799\" height=\"533\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53659943218_fffff37491_c.jpg\" alt=\"\" class=\"wp-image-20791\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53659943218_fffff37491_c.jpg 799w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53659943218_fffff37491_c-300x200.jpg 300w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53659943218_fffff37491_c-768x512.jpg 768w\" sizes=\"auto, (max-width: 799px) 100vw, 799px\" \/><\/figure>\n\n\n\n<p><strong>Laval Virtual means fun, unforgettable evenings too, especially the renowned Laval Virtual Party!<\/strong> By associating your organisation with this event, you&#8217;ll benefit from exceptional visibility within the VR\/AR community (and a great time!).<br><\/p>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-base-2-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"testimonials alignwide swiper-container\">\n    \n    <div class=\"testimonials-slider swiper-wrapper\">\n                    <div class=\"testimonial swiper-slide\">\n                                    <div class=\"testimonial__picture\">\n                        <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/06\/Lauren_Herbert-Synergiz.jpeg\" alt=\"\">\n                    <\/div>\n                                \n                <div class=\"testimonial__name\">Lauren HERBERT<\/div>\n                <div class=\"testimonial__job\">Directrice Marketing, Communication et Partenariats, Synergiz<\/div>\n                                    <div class=\"testimonial__company-logo\">\n                        <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/03\/d90159d0bd27-Synergiz_logo_fd_transparent.png\" alt=\"\" height=\"20px\">\n                    <\/div>\n                                <div class=\"testimonial__text\">Laval Virtual est LE rendez-vous incontournable pour nous retrouver entre pairs et rencontrer de nouveaux partenaires et clients !<\/div>\n                \n            <\/div>\n                    <div class=\"testimonial swiper-slide\">\n                                    <div class=\"testimonial__picture\">\n                        <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/06\/Chloe-SCHRIJNEMA.jpeg\" alt=\"\">\n                    <\/div>\n                                \n                <div class=\"testimonial__name\">Chloe SCHRIJNEMAEKERS<\/div>\n                <div class=\"testimonial__job\">Responsable Marketing, SenseGlove<\/div>\n                                    <div class=\"testimonial__company-logo\">\n                        <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/02\/LOGO-SENSEGLOVE-2.jpeg\" alt=\"\" height=\"20px\">\n                    <\/div>\n                                <div class=\"testimonial__text\">Laval Virtual 2024 a \u00e9t\u00e9 un \u00e9v\u00e9nement enrichissant. Nous avons eu le plaisir de mettre en contact plusieurs acteurs majeurs de l&#8217;industrie XR et de pr\u00e9senter notre derni\u00e8re technologie haptique \u00e0 des personnes partageant les m\u00eames id\u00e9es.<\/div>\n                \n            <\/div>\n                    <div class=\"testimonial swiper-slide\">\n                                    <div class=\"testimonial__picture\">\n                        <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/06\/Franck-Darmon.jpeg\" alt=\"\">\n                    <\/div>\n                                \n                <div class=\"testimonial__name\">Franck DARMON<\/div>\n                <div class=\"testimonial__job\">CEO, CARRI Systems<\/div>\n                                    <div class=\"testimonial__company-logo\">\n                        <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/03\/CARRI_SYSTEMS_HD__baseline-1.jpg\" alt=\"Carri Systems\" height=\"20px\">\n                    <\/div>\n                                <div class=\"testimonial__text\">Carri Systems est fier de faire partie de la sc\u00e8ne VR\/AR depuis de nombreuses ann\u00e9es et continuera \u00e0 le faire dans un avenir pr\u00e9visible. F\u00e9licitations \u00e0 l&#8217;\u00e9quipe et au personnel pour cet \u00e9v\u00e9nement de classe mondiale !<\/div>\n                \n            <\/div>\n            <\/div>\n    <div class=\"testimonials__nav\">\n        <div class=\"swiper-button-prev\"><\/div>\n        <div class=\"swiper-button-next\"><\/div>\n    <\/div>\n    <div class=\"swiper-pagination\"><\/div>\n<\/div>\n<script src=\"https:\/\/staging.laval-virtual.com\/wp-content\/themes\/laval-virtual-2025\/external\/swiper.min.js\"><\/script>\n<script>\n    const testimonials = document.querySelector('.testimonials');\n    const tesimonialsSlider = new Swiper(testimonials, {\n        slidesPerView: 1,\n        loop: true,\n        speed: 1000,\n        watchSlidesProgress: true,\n        autoplay: {\n            delay: 5000,\n        },\n        navigation: {\n            nextEl: '.testimonials__nav .swiper-button-next',\n            prevEl: '.testimonials__nav .swiper-button-prev',\n        },\n        pagination: {\n            el: '.swiper-pagination',\n            clickable: true,\n        },\n    });\n<\/script><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-base-2-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<swiper-container class=\"sponsors-carousel alignwide\" speed=\"500\" loop=\"true\" autoplay=\"true\" space-between=\"100\" \nbreakpoints='{\n        \"1024\": {\n            \"slidesPerView\": 5,\n            \"spaceBetween\": 100\n        },\n        \"768\": {\n            \"slidesPerView\": 4,\n            \"spaceBetween\": 90\n        },\n        \"640\": {\n            \"slidesPerView\": 3,\n            \"spaceBetween\": 80\n        },\n        \"320\": {\n            \"slidesPerView\": 2,\n            \"spaceBetween\": 40\n        }\n    }'\n>\n            <swiper-slide>\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/04\/MimicProduction_Logo.png\" alt=\"\">\n        <\/swiper-slide>\n            <swiper-slide>\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/04\/CEA-List.png\" alt=\"\">\n        <\/swiper-slide>\n            <swiper-slide>\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/04\/Enephetys-Logo-noirfondtransparent.png\" alt=\"\">\n        <\/swiper-slide>\n            <swiper-slide>\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/04\/LOGO-EREEL-BL-POSITIF-RVB.png\" alt=\"\">\n        <\/swiper-slide>\n            <swiper-slide>\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/04\/Dreaming-of-Lebanon.jpg\" alt=\"\">\n        <\/swiper-slide>\n            <swiper-slide>\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/02\/pic5276-4.png\" alt=\"\">\n        <\/swiper-slide>\n            <swiper-slide>\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/12\/pic9.jpg\" alt=\"\">\n        <\/swiper-slide>\n            <swiper-slide>\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/03\/pic5582-3.jpg\" alt=\"\">\n        <\/swiper-slide>\n            <swiper-slide>\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/11\/pic5528-3.png\" alt=\"\">\n        <\/swiper-slide>\n    <\/swiper-container><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"margin-bottom:var(--wp--preset--spacing--60)\">OUR B2B CONFERENCES<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\"> \n\n<div class=\"programme\">\n    <nav>\n        <ul>\n                            <li><a href=\"#\" data-date=\"09-04-2025\" class=\"active\">April 9<\/a><\/li>\n                            <li><a href=\"#\" data-date=\"10-04-2025\" class=\"\">April 10<\/a><\/li>\n                            <li><a href=\"#\" data-date=\"11-04-2025\" class=\"\">April 11<\/a><\/li>\n                    <\/ul>\n    <\/nav>\n    <div class=\"events\">\n\n                <a class=\"event\" href=\"https:\/\/staging.laval-virtual.com\/en\/conference_cycle\/xr-devices-technologies\/\">\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53658899077_0c2b76ed1c_c.jpg\" class=\"event__img\" alt=\"\">\n            <div class=\"event__info\" data-date=\"09-04-2025\" data-starttime= \"10:30 am\" data-endtime=\"12:30 pm\">\n                <div class=\"time\">10:30 am &#8211; 12:30 pm<\/div>\n                <div class=\"title\">Spotlight on XR Devices and Technologies<\/div>\n                <div class=\"description\">Join us for a series of morning conferences exploring the latest innovations and trends in XR technology. This event will provide insights into the performance, ergonomics, and long-term use of the leading XR hardware in the market. We\u2019ll also discuss key societal issues, including the impact and sustainability of these devices.<\/div>\n                            <\/div>\n        <\/a>\n                <a class=\"event\" href=\"https:\/\/staging.laval-virtual.com\/en\/conference_cycle\/xr-everywhere\/\">\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53660118789_64593c7a2c_c.jpg\" class=\"event__img\" alt=\"\">\n            <div class=\"event__info\" data-date=\"09-04-2025\" data-starttime= \"02:00 pm\" data-endtime=\"05:00 pm\">\n                <div class=\"time\">02:00 pm &#8211; 05:00 pm<\/div>\n                <div class=\"title\">XR Everywhere<\/div>\n                <div class=\"description\">From tourist attractions, museums, and theme parks to shopping malls\u2014discover how XR is revolutionizing entertainment, culture, and even everyday environments like transportation and healthcare. Uncover the unexpected ways immersive technologies are shaping practices and solving today\u2019s and tomorrow\u2019s challenges.<\/div>\n                            <\/div>\n        <\/a>\n                <a class=\"event\" href=\"https:\/\/staging.laval-virtual.com\/en\/conference_cycle\/immersive-simulations-and-engineering-innovation\/\">\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53659983943_244577db46_c.jpg\" class=\"event__img\" alt=\"\">\n            <div class=\"event__info\" data-date=\"10-04-2025\" data-starttime= \"10:00 am\" data-endtime=\"12:30 pm\">\n                <div class=\"time\">10:00 am &#8211; 12:30 pm<\/div>\n                <div class=\"title\">Immersive Simulations and Innovation in Engineering<\/div>\n                <div class=\"description\">Digital twins and immersive simulations are transforming design and engineering. These cutting-edge technologies are revolutionizing processes by providing more flexible, responsive, and efficient tools. Discover real-world case studies and hear from industry professionals about how these innovations are reshaping their fields.<\/div>\n                            <\/div>\n        <\/a>\n                <a class=\"event\" href=\"https:\/\/staging.laval-virtual.com\/en\/conference_cycle\/ai-powered-virtual-characters-assistants\/\">\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/robot-7014652_1280.jpg\" class=\"event__img\" alt=\"\">\n            <div class=\"event__info\" data-date=\"10-04-2025\" data-starttime= \"01:30 pm\" data-endtime=\"03:30 pm\">\n                <div class=\"time\">01:30 pm &#8211; 03:30 pm<\/div>\n                <div class=\"title\">AI-Driven Virtual Characters and Avatars<\/div>\n                <div class=\"description\">Discover how AI-powered avatars are redefining interaction in virtual environments, whether for industrial simulations, training or retail. Explore how the combination of AI and immersive technologies is creating intelligent virtual assistants that are changing the landscape of virtual interaction.<\/div>\n                            <\/div>\n        <\/a>\n                <a class=\"event\" href=\"https:\/\/staging.laval-virtual.com\/en\/conference_cycle\/delight-your-customers-with-xr\/\">\n            <img decoding=\"async\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53660226535_dd23106a14_c.jpg\" class=\"event__img\" alt=\"\">\n            <div class=\"event__info\" data-date=\"11-04-2025\" data-starttime= \"10:00 am\" data-endtime=\"12:30 pm\">\n                <div class=\"time\">10:00 am &#8211; 12:30 pm<\/div>\n                <div class=\"title\">Expanding Your Customer Base with XR<\/div>\n                <div class=\"description\">Elevate your brand experience with XR technology. Learn how immersive technologies can enhance your sales processes, boost conversion rates, and increase customer loyalty. Discover best practices and real-world case studies to inspire your strategy.<\/div>\n                            <\/div>\n        <\/a>\n            <\/div>\n    <script>\n        const nav = document.querySelector('.programme nav');\n        const events = document.querySelectorAll('.programme .event');\n\n        events.forEach(event => {\n            const date = event.querySelector('.event__info').dataset.date;\n            if(date != nav.querySelector('a').dataset.date) {\n                event.style.display = 'none';\n            }\n        })\n\n        nav.addEventListener('click', (e) => {\n            e.preventDefault();\n            const date = e.target.dataset.date;\n            if(date) {\n                const active = document.querySelector('.programme nav .active');\n                active.classList.remove('active');\n                e.target.classList.add('active');\n                events.forEach(event => {\n                    if(event.querySelector('.event__info').dataset.date == date) {\n                        event.style.display = 'flex';\n                    } else {\n                        event.style.display = 'none';\n                    }\n                })\n            }\n        })\n\n    <\/script>\n    \n<\/div><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-darkblue-color has-text-color has-large-font-size\"><strong>The press on hand<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-center\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">Every year, a wide range of media come to Laval Virtual to report on the latest innovations.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"155\" src=\"http:\/\/lavalvirtual.local\/wp-content\/uploads\/2023\/05\/bando-logos-medias-lv2023-2-1024x155.png\" alt=\"\" class=\"wp-image-10451\" srcset=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/05\/bando-logos-medias-lv2023-2-1024x155.png 1024w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/05\/bando-logos-medias-lv2023-2-300x45.png 300w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/05\/bando-logos-medias-lv2023-2-768x116.png 768w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/05\/bando-logos-medias-lv2023-2.png 1193w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\">\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Find out more about VR all year round<\/strong><\/h3>\n<\/div>\n\n\n\n<div class=\"articles\">\n    <\/div>\n\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-cover alignwide is-style-cover-cta is-style-cover-cta--4\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:var(--wp--preset--spacing--40);padding-bottom:var(--wp--preset--spacing--40);padding-left:var(--wp--preset--spacing--40);min-height:325px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-accent-background-color has-background-dim-70 has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1154\" class=\"wp-block-cover__image-background wp-image-22223\" alt=\"\" src=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/20240409_202531-scaled.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/20240409_202531-scaled.jpg 2560w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/20240409_202531-300x135.jpg 300w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/20240409_202531-1024x462.jpg 1024w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/20240409_202531-768x346.jpg 768w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/20240409_202531-1536x692.jpg 1536w, https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/20240409_202531-2048x923.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center has-white-color has-text-color has-large-font-size\" style=\"margin-right:var(--wp--preset--spacing--30);margin-left:var(--wp--preset--spacing--30);padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">The event dedicated to VR\/AR<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-gradient-3-gradient-background has-background wp-element-button\" href=\"http:\/\/lavalvirtual.local\/billetterie\/\" target=\"_blank\" rel=\"noreferrer noopener\">GET YOUR PASS<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>27th edition from 9 to 11 April 2025 Laval virtual: europe&#8217;s biggest xr event Laval Virtual, the leading event dedicated to immersive technologies (virtual reality, augmented reality, spatial computing, etc.), [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":20754,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10093","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Laval Virtual | from 9 to 11 april 2025<\/title>\n<meta name=\"description\" content=\"Laval Virtual is the 1st professional event dedicated to immersive technologies (VR\/AR). Take part in the leading VR\/AR event.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laval Virtual\" \/>\n<meta property=\"og:description\" content=\"Laval Virtual is the leading event dedicated to immersive technologies (VR\/AR). It has brought together the entire XR community since 1999. The 26th edition will be held from 10 to 12 April 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/\" \/>\n<meta property=\"og:site_name\" content=\"Laval Virtual\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T13:15:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/10\/Event-LinkedIn.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Laval Virtual\" \/>\n<meta name=\"twitter:description\" content=\"Laval Virtual is the leading event dedicated to immersive technologies (VR\/AR). It has brought together the entire XR community since 1999. The 26th edition will be held from 10 to 12 April 2024.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/10\/Event-LinkedIn.png\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/\",\"url\":\"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/\",\"name\":\"Laval Virtual | from 9 to 11 april 2025\",\"isPartOf\":{\"@id\":\"https:\/\/staging.laval-virtual.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53660226620_0a987eb120_c.jpg\",\"datePublished\":\"2023-05-03T13:16:08+00:00\",\"dateModified\":\"2025-01-23T13:15:56+00:00\",\"description\":\"Laval Virtual is the 1st professional event dedicated to immersive technologies (VR\/AR). Take part in the leading VR\/AR event.\",\"breadcrumb\":{\"@id\":\"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/#primaryimage\",\"url\":\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53660226620_0a987eb120_c.jpg\",\"contentUrl\":\"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53660226620_0a987eb120_c.jpg\",\"width\":799,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laval Virtual 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/staging.laval-virtual.com\/#website\",\"url\":\"https:\/\/staging.laval-virtual.com\/\",\"name\":\"Laval Virtual\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/staging.laval-virtual.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laval Virtual | from 9 to 11 april 2025","description":"Laval Virtual is the 1st professional event dedicated to immersive technologies (VR\/AR). Take part in the leading VR\/AR event.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Laval Virtual","og_description":"Laval Virtual is the leading event dedicated to immersive technologies (VR\/AR). It has brought together the entire XR community since 1999. The 26th edition will be held from 10 to 12 April 2024.","og_url":"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/","og_site_name":"Laval Virtual","article_modified_time":"2025-01-23T13:15:56+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/10\/Event-LinkedIn.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Laval Virtual","twitter_description":"Laval Virtual is the leading event dedicated to immersive technologies (VR\/AR). It has brought together the entire XR community since 1999. The 26th edition will be held from 10 to 12 April 2024.","twitter_image":"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2023\/10\/Event-LinkedIn.png","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/","url":"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/","name":"Laval Virtual | from 9 to 11 april 2025","isPartOf":{"@id":"https:\/\/staging.laval-virtual.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/#primaryimage"},"image":{"@id":"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53660226620_0a987eb120_c.jpg","datePublished":"2023-05-03T13:16:08+00:00","dateModified":"2025-01-23T13:15:56+00:00","description":"Laval Virtual is the 1st professional event dedicated to immersive technologies (VR\/AR). Take part in the leading VR\/AR event.","breadcrumb":{"@id":"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/#primaryimage","url":"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53660226620_0a987eb120_c.jpg","contentUrl":"https:\/\/staging.laval-virtual.com\/wp-content\/uploads\/2024\/07\/53660226620_0a987eb120_c.jpg","width":799,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/staging.laval-virtual.com\/en\/laval-virtual\/"},{"@type":"ListItem","position":2,"name":"Laval Virtual 2025"}]},{"@type":"WebSite","@id":"https:\/\/staging.laval-virtual.com\/#website","url":"https:\/\/staging.laval-virtual.com\/","name":"Laval Virtual","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.laval-virtual.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/staging.laval-virtual.com\/en\/wp-json\/wp\/v2\/pages\/10093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.laval-virtual.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.laval-virtual.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.laval-virtual.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.laval-virtual.com\/en\/wp-json\/wp\/v2\/comments?post=10093"}],"version-history":[{"count":28,"href":"https:\/\/staging.laval-virtual.com\/en\/wp-json\/wp\/v2\/pages\/10093\/revisions"}],"predecessor-version":[{"id":25400,"href":"https:\/\/staging.laval-virtual.com\/en\/wp-json\/wp\/v2\/pages\/10093\/revisions\/25400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.laval-virtual.com\/en\/wp-json\/wp\/v2\/media\/20754"}],"wp:attachment":[{"href":"https:\/\/staging.laval-virtual.com\/en\/wp-json\/wp\/v2\/media?parent=10093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}